{"id":18567,"date":"2024-09-06T12:29:04","date_gmt":"2024-09-06T10:29:04","guid":{"rendered":"https:\/\/fvcomponentes.com\/?post_type=product&#038;p=18567"},"modified":"2026-07-15T19:56:53","modified_gmt":"2026-07-15T17:56:53","slug":"magnetothermischer-chint-nbh8-40-c20-20a-c-45ka-nbh8-1n-20c4-5","status":"publish","type":"product","link":"https:\/\/fvcomponentes.com\/de\/producto\/magnetotermico-chint-nbh8-40-c20-20a-c-45ka-nbh8-1n-20c4-5\/","title":{"rendered":"Schmaler Leitungsschutzschalter 1P+N 20A 4,5kA Chint - NBH8-1N-20C4.5"},"content":{"rendered":"<h2>Merkmale 1P+N 20A 4,5kA Chint - NBH8-1N-20C4.5<\/h2>\n<h2>Elektrische Eigenschaften<\/h2>\n<ul>\n<li>Nennstrom: 20A<\/li>\n<li>Pole: 1P+N<\/li>\n<li>Nennspannung Ue: 230\/240V<\/li>\n<li>Isolationsspannung Ui: 500V<\/li>\n<li>Nennfrequenz: 50\/60Hz<\/li>\n<li>Abschaltleistung: 4500\/6000A<\/li>\n<li>Bemessungs-Sto\u00dfspannung (1.2\/50) Uimp: 4000V<\/li>\n<li>Dielektrische Pr\u00fcfspannung bei Gleichstrom f\u00fcr 1 Minute: 2kV<\/li>\n<li>Grad der Verschmutzung: 2<\/li>\n<li>Energiebegrenzungsklasse: 3<\/li>\n<\/ul>\n<h2>Mechanische Eigenschaften<\/h2>\n<ul>\n<li>Elektrische Lebensdauer: 8000<\/li>\n<li>Mechanische Lebensdauer: 20000<\/li>\n<li>Kontaktstellungsanzeige: ja<\/li>\n<li>Schutzart: IP20<\/li>\n<li>Referenztemperatur f\u00fcr die Anpassung an das Heizelement: 30\u2103.<\/li>\n<li>Umgebungstemperatur (mit einem Tagesdurchschnitt\u226435\u2103): -5...+40\u2103<\/li>\n<li>Lagertemperatur: -25...+70\u2103<\/li>\n<\/ul>\n<h2>Datenblatt Schmaler Leitungsschutzschalter 1P+N 20A 4,5kA Chint - NBH8-1N-20C4.5<\/h2>\n<p><a href=\"https:\/\/fvcomponentes.com\/wp-content\/uploads\/2024\/09\/Ficha-tecnica-Magnetotermico-Chint-NBH8.pdf\" target=\"_blank\" rel=\"noopener\">Siehe das technische Datenblatt des 1P+N 20A 4,5kA Chint - NBH8-1N-20C4.5<br \/>\n<\/a><\/p>","protected":false},"excerpt":{"rendered":"<ul>\n<li>Kurve C<\/li>\n<li>Nennstrom: 20A<\/li>\n<li>Pole: 1P+N<\/li>\n<li>Nennspannung Ue: 230\/240V<\/li>\n<li>Isolationsspannung Ui: 500V<\/li>\n<\/ul>\n<p>Das Produktfoto dient nur zur Veranschaulichung und entspricht m\u00f6glicherweise nicht dem tats\u00e4chlichen Produkt.<\/p>","protected":false},"featured_media":18568,"comment_status":"open","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}}},"pwb-brand":[999],"product_brand":[],"product_cat":[990,410],"product_tag":[],"class_list":["post-18567","product","type-product","status-publish","has-post-thumbnail","pwb-brand-chint","product_cat-magnetotermicos","product_cat-material-electrico","desktop-align-left","tablet-align-left","mobile-align-left","ast-product-gallery-layout-horizontal-slider","ast-product-gallery-with-no-image","ast-product-tabs-layout-horizontal","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"wcpa_form_fields":null,"brands":[{"id":999,"name":"Chint","slug":"chint"}],"_links":{"self":[{"href":"https:\/\/fvcomponentes.com\/de\/wp-json\/wp\/v2\/product\/18567","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fvcomponentes.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/fvcomponentes.com\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/fvcomponentes.com\/de\/wp-json\/wp\/v2\/comments?post=18567"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fvcomponentes.com\/de\/wp-json\/wp\/v2\/media\/18568"}],"wp:attachment":[{"href":"https:\/\/fvcomponentes.com\/de\/wp-json\/wp\/v2\/media?parent=18567"}],"wp:term":[{"taxonomy":"pwb-brand","embeddable":true,"href":"https:\/\/fvcomponentes.com\/de\/wp-json\/wp\/v2\/pwb-brand?post=18567"},{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/fvcomponentes.com\/de\/wp-json\/wp\/v2\/product_brand?post=18567"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/fvcomponentes.com\/de\/wp-json\/wp\/v2\/product_cat?post=18567"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/fvcomponentes.com\/de\/wp-json\/wp\/v2\/product_tag?post=18567"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}